{"id":9244,"date":"2022-03-08T19:43:23","date_gmt":"2022-03-08T12:43:23","guid":{"rendered":"https:\/\/web.oshikrub.com\/maeloi\/?page_id=9244"},"modified":"2023-10-17T13:42:15","modified_gmt":"2023-10-17T06:42:15","slug":"e-service-%e0%b8%84%e0%b8%b3%e0%b8%a3%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%82%e0%b8%ad%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%ad%e0%b8%99%e0%b9%84","status":"publish","type":"page","link":"https:\/\/www.maeloi.go.th\/home\/e-service-%e0%b8%84%e0%b8%b3%e0%b8%a3%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b8%82%e0%b8%ad%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%ad%e0%b8%99%e0%b9%84\/","title":{"rendered":"E-Service  \u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9244\" class=\"elementor elementor-9244\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22b47ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22b47ea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61553ba\" data-id=\"61553ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-677897d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"677897d\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-61e5efc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61e5efc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-603c2a6\" data-id=\"603c2a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7eea3e elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"f7eea3e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfHh92C0wLnuZNa-X801CP4GIhnudUPVKMXXABrD3A_OMDd6g\/viewform?usp=sf_link\" target=\"_blank\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"639\" height=\"450\" src=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/man-cutting-tree-6706826-5605897.png\" class=\"elementor-animation-pop attachment-full size-full wp-image-15626\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfHh92C0wLnuZNa-X801CP4GIhnudUPVKMXXABrD3A_OMDd6g\/viewform?usp=sf_link\" target=\"_blank\">\u0e04\u0e33\u0e02\u0e2d\u0e15\u0e31\u0e14\u0e01\u0e34\u0e48\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49<\/a><\/div><p class=\"elementor-image-box-description\">\u0e43\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e1a\u0e15.\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d601e48\" data-id=\"d601e48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3245002 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"3245002\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSci5M4-LlxorCXDZPm6uwpxZ2VFGx67FH7tDNsfYrqdvSOzqw\/viewform?usp=sf_link\" target=\"_blank\" tabindex=\"-1\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/266-2668025_drinking-water-symbol-symbol-of-drinking-water.png\" class=\"elementor-animation-pop attachment-full size-full wp-image-15625\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSci5M4-LlxorCXDZPm6uwpxZ2VFGx67FH7tDNsfYrqdvSOzqw\/viewform?usp=sf_link\" target=\"_blank\">\u0e04\u0e33\u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e19\u0e49\u0e33\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2d\u0e38\u0e1b\u0e42\u0e20\u0e04\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04<\/a><\/div><p class=\"elementor-image-box-description\">\u0e43\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e1a\u0e15.\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4e06655\" data-id=\"4e06655\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c56e3c elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"9c56e3c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSd7F0CIPusYJvqBiGqcHasWm_PfR2PhJXss4wDsaOekAXwmhw\/viewform?usp=sf_link\" target=\"_blank\" tabindex=\"-1\"><img decoding=\"async\" width=\"300\" height=\"263\" src=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/electric-power-sign-logo-53587F7AC4-seeklogo.com_.png\" class=\"elementor-animation-pop attachment-full size-full wp-image-15624\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\"><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSd7F0CIPusYJvqBiGqcHasWm_PfR2PhJXss4wDsaOekAXwmhw\/viewform?usp=sf_link\" target=\"_blank\">\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e0b\u0e48\u0e2d\u0e21\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30<\/a><\/div><p class=\"elementor-image-box-description\">\u0e43\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e1a\u0e15.\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-817115f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"817115f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-55c3ec5\" data-id=\"55c3ec5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28e6812 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"28e6812\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"#\" target=\"_blank\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/2885648.png\" class=\"elementor-animation-pop attachment-full size-full wp-image-15550\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\"><a href=\"#\" target=\"_blank\">\u0e41\u0e08\u0e49\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b<\/a><\/div><p class=\"elementor-image-box-description\">\u0e43\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e1a\u0e15.\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d37637a\" data-id=\"d37637a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9532c4e\" data-id=\"9532c4e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-62a050f\" data-id=\"62a050f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bda0cf2 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget elementor-widget-divider\" data-id=\"bda0cf2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dfc9d4 elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"7dfc9d4\" data-element_type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;vertical&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-7dfc9d4\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7232\"><a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%95%e0%b8%b4-%e0%b8%ad%e0%b8%9a%e0%b8%95-%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b8%ad%e0%b9%89%e0%b8%ad\/\" class=\"elementor-item\">\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34 \u0e2d\u0e1a\u0e15.\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7233\"><a href=\"https:\/\/www.maeloi.go.th\/home\/general\/\" class=\"elementor-item\">\u0e2a\u0e20\u0e32\u0e1e\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7234\"><a href=\"https:\/\/www.maeloi.go.th\/home\/vision\/\" class=\"elementor-item\">\u0e04\u0e33\u0e02\u0e27\u0e31\u0e0d \u0e27\u0e34\u0e2a\u0e31\u0e22\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e1e\u0e31\u0e19\u0e18\u0e01\u0e34\u0e08<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9498\"><a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9e%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%b2%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%b8%e0%b9%89%e0%b8%9a%e0%b8%a3\/\" class=\"elementor-item\">\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7236\"><a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%88%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2%e0%b8%a3\/\" class=\"elementor-item\">\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7dfc9d4\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7232\"><a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%a7%e0%b8%b1%e0%b8%95%e0%b8%b4-%e0%b8%ad%e0%b8%9a%e0%b8%95-%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b8%ad%e0%b9%89%e0%b8%ad\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34 \u0e2d\u0e1a\u0e15.\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7233\"><a href=\"https:\/\/www.maeloi.go.th\/home\/general\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2a\u0e20\u0e32\u0e1e\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7234\"><a href=\"https:\/\/www.maeloi.go.th\/home\/vision\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e04\u0e33\u0e02\u0e27\u0e31\u0e0d \u0e27\u0e34\u0e2a\u0e31\u0e22\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e1e\u0e31\u0e19\u0e18\u0e01\u0e34\u0e08<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-9498\"><a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%99%e0%b9%82%e0%b8%a2%e0%b8%9a%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9e%e0%b8%b1%e0%b8%92%e0%b8%99%e0%b8%b2%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b8%9c%e0%b8%b8%e0%b9%89%e0%b8%9a%e0%b8%a3\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7236\"><a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%88%e0%b8%ab%e0%b8%99%e0%b9%89%e0%b8%b2%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%82%e0%b8%ad%e0%b8%87%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2%e0%b8%a3\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2d\u0e33\u0e19\u0e32\u0e08\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c447de0 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget elementor-widget-divider\" data-id=\"c447de0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10ff0d5 elementor-grid-1 elementor-posts--thumbnail-left elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"10ff0d5\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-49502 post type-post status-publish format-standard has-post-thumbnail hentry category-46\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b9%80%e0%b8%82%e0%b9%89%e0%b8%b2%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%84%e0%b8%b8%e0%b8%93\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2026\/09\/790399338_1403647331703559_425230709778460890_n-300x200.jpg\" class=\"attachment-medium size-medium wp-image-49508\" alt=\"\" srcset=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2026\/09\/790399338_1403647331703559_425230709778460890_n-300x200.jpg 300w, https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2026\/09\/790399338_1403647331703559_425230709778460890_n-768x512.jpg 768w, https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2026\/09\/790399338_1403647331703559_425230709778460890_n.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b9%80%e0%b8%82%e0%b9%89%e0%b8%b2%e0%b8%a3%e0%b9%88%e0%b8%a7%e0%b8%a1%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%9a%e0%b8%a3%e0%b8%a1%e0%b8%84%e0%b8%b8%e0%b8%93\/\" >\n\t\t\t\t\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e04\u0e38\u0e13\u0e18\u0e23\u0e23\u0e21 \u0e08\u0e23\u0e34\u0e22\u0e18\u0e23\u0e23\u0e21 (\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e39\u0e19\u0e17\u0e31\u0e01\u0e29\u0e30 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23) \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28. 2569\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-49476 post type-post status-publish format-standard has-post-thumbnail hentry category-46\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b9%80%e0%b8%aa%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%ad%e0%b8%9a%e0%b8%9b%e0%b8%a3\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2026\/09\/793212613_1414451557452051_9127584010704910860_n-300x225.jpg\" class=\"attachment-medium size-medium wp-image-49486\" alt=\"\" srcset=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2026\/09\/793212613_1414451557452051_9127584010704910860_n-300x225.jpg 300w, https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2026\/09\/793212613_1414451557452051_9127584010704910860_n-768x577.jpg 768w, https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2026\/09\/793212613_1414451557452051_9127584010704910860_n.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b9%88%e0%b8%87%e0%b9%80%e0%b8%aa%e0%b8%a3%e0%b8%b4%e0%b8%a1%e0%b8%a3%e0%b8%b0%e0%b8%9a%e0%b8%ad%e0%b8%9a%e0%b8%9b%e0%b8%a3\/\" >\n\t\t\t\t\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e23\u0e30\u0e1a\u0e2d\u0e1a\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e18\u0e34\u0e1b\u0e44\u0e15\u0e22 \u0e2d\u0e31\u0e19\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e29\u0e31\u0e15\u0e23\u0e34\u0e22\u0e4c\u0e17\u0e23\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e23\u0e30\u0e1b\u0e23\u0e30\u0e21\u0e38\u0e02 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2569\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-49288 post type-post status-publish format-standard has-post-thumbnail hentry category-1\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b9%88-50\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"115\" src=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/DF-MAELOI-BG.jpg\" class=\"attachment-medium size-medium wp-image-16176\" alt=\"\" srcset=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/DF-MAELOI-BG.jpg 980w, https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/DF-MAELOI-BG-768x294.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b9%88-50\/\" >\n\t\t\t\t\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e16\u0e19\u0e19\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01 (\u0e0a\u0e19\u0e34\u0e14\u0e44\u0e21\u0e48\u0e21\u0e35\u0e44\u0e2b\u0e25\u0e48\u0e17\u0e32\u0e07) \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e2d\u0e07\u0e02\u0e48\u0e27\u0e07 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 11 \u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e17\u0e34\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-49286 post type-post status-publish format-standard has-post-thumbnail hentry category-1\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b9%88-49\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"115\" src=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/DF-MAELOI-BG.jpg\" class=\"attachment-medium size-medium wp-image-16176\" alt=\"\" srcset=\"https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/DF-MAELOI-BG.jpg 980w, https:\/\/www.maeloi.go.th\/home\/wp-content\/uploads\/2023\/10\/DF-MAELOI-BG-768x294.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.maeloi.go.th\/home\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%ad%e0%b8%87%e0%b8%84%e0%b9%8c%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b9%88-49\/\" >\n\t\t\t\t\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e04\u0e2d\u0e19\u0e01\u0e23\u0e35\u0e15\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e40\u0e2b\u0e25\u0e47\u0e01 (\u0e23\u0e39\u0e1b\u0e15\u0e31\u0e27\u0e22\u0e39) \u0e0a\u0e19\u0e34\u0e14\u0e21\u0e35\u0e1d\u0e32\u0e1b\u0e34\u0e14 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e49\u0e27\u0e22\u0e19\u0e48\u0e32\u0e19 \u0e2b\u0e21\u0e39\u0e48\u0e17\u0e35\u0e48 4 \u0e15\u0e33\u0e1a\u0e25\u0e41\u0e21\u0e48\u0e25\u0e2d\u0e22 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e40\u0e17\u0e34\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e23\u0e32\u0e22\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e33\u0e02\u0e2d\u0e15\u0e31\u0e14\u0e01\u0e34\u0e48\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 \u0e43\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37<\/p>\n","protected":false},"author":1,"featured_media":16176,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9244","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.maeloi.go.th\/home\/wp-json\/wp\/v2\/pages\/9244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maeloi.go.th\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.maeloi.go.th\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.maeloi.go.th\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maeloi.go.th\/home\/wp-json\/wp\/v2\/comments?post=9244"}],"version-history":[{"count":0,"href":"https:\/\/www.maeloi.go.th\/home\/wp-json\/wp\/v2\/pages\/9244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maeloi.go.th\/home\/wp-json\/wp\/v2\/media\/16176"}],"wp:attachment":[{"href":"https:\/\/www.maeloi.go.th\/home\/wp-json\/wp\/v2\/media?parent=9244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}